{"id":647,"date":"2015-08-26T22:57:58","date_gmt":"2015-08-26T20:57:58","guid":{"rendered":"http:\/\/patchwerkstatt.kowalke-net.de\/pw2\/?p=647"},"modified":"2015-09-25T19:43:59","modified_gmt":"2015-09-25T17:43:59","slug":"schattenspiele","status":"publish","type":"post","link":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/schattenspiele\/","title":{"rendered":"Schattenspiele"},"content":{"rendered":"<p><a href=\"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-content\/uploads\/2015\/08\/Schattenspiele_KP.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-648 alignright\" src=\"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-content\/uploads\/2015\/08\/Schattenspiele_KP-300x295.jpg\" alt=\"Schattenspiele_KP\" width=\"300\" height=\"295\" srcset=\"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-content\/uploads\/2015\/08\/Schattenspiele_KP-300x295.jpg 300w, https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-content\/uploads\/2015\/08\/Schattenspiele_KP-500x492.jpg 500w, https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-content\/uploads\/2015\/08\/Schattenspiele_KP-153x150.jpg 153w, https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-content\/uploads\/2015\/08\/Schattenspiele_KP.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Der Schatten l\u00e4sst die Formen dreidimensional wirken. Viele Motive eignen sich f\u00fcr Schattenmuster, frei geschnitten oder exakt gemessen. Sie k\u00f6nnen unter verschiedenen Modellen w\u00e4hlen.<\/p>\n<p><strong>1 Kurstag &#8211; Kursgeb\u00fchr \u20ac 12,-<\/strong><\/p>\n\n    <div id=\"eventsbymike_eventsbypost\">\n      <table border=\"1\">\n          <tr>\n          \t<td><\/td>\n          \t<td>Dienstag,<\/td>\n          \t<td>29. September 2015<\/td>\n          \t<td>18:00 - 21:00 Uhr<\/td>\n          <\/tr>\n          <tr>\n          \t<td><\/td>\n          \t<td>Mittwoch,<\/td>\n          \t<td>07. Oktober 2015<\/td>\n          \t<td>08:30 - 11:30 Uhr<\/td>\n          <\/tr>\n      <\/table>\n    <\/div>\n<div class=\"twoclick_social_bookmarks_post_647 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_647')){$('.twoclick_social_bookmarks_post_647').socialSharePrivacy({\"services\":{\"facebook\":{\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Facebook senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"action\":\"like\",\"language\":\"de_DE\"},\"gplus\":{\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Google+ senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"referrer_track\":\"\"}},\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/patchwerkstatt.kowalke-net.de\\\/pw2\\\/schattenspiele\\\/\",\"post_id\":647,\"post_title_referrer_track\":\"Schattenspiele\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>Der Schatten l\u00e4sst die Formen dreidimensional wirken. Viele Motive eignen sich f\u00fcr Schattenmuster, frei geschnitten oder exakt gemessen. Sie k\u00f6nnen unter verschiedenen Modellen w\u00e4hlen. 1 Kurstag &#8211; Kursgeb\u00fchr \u20ac 12,- Dienstag, 29. September 2015 18:00 &#8211; 21:00 Uhr Mittwoch, 07. Oktober 2015 08:30 &#8211; 11:30 Uhr<\/p>\n","protected":false},"author":3,"featured_media":648,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[12,70,31],"class_list":["post-647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kurs","tag-freies-schneiden","tag-kurs","tag-modern"],"_links":{"self":[{"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/posts\/647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/comments?post=647"}],"version-history":[{"count":1,"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/posts\/647\/revisions"}],"predecessor-version":[{"id":649,"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/posts\/647\/revisions\/649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/media\/648"}],"wp:attachment":[{"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/media?parent=647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/categories?post=647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patchwerkstatt.kowalke-net.de\/pw2\/wp-json\/wp\/v2\/tags?post=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}